{"id":11710,"date":"2022-09-04T21:10:23","date_gmt":"2022-09-04T19:10:23","guid":{"rendered":"https:\/\/eeclectic.de\/?p=11710"},"modified":"2023-02-03T17:50:34","modified_gmt":"2023-02-03T16:50:34","slug":"diskussion-berliner-hefte","status":"publish","type":"post","link":"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/","title":{"rendered":"DISKUSSION BERLINER HEFTE 2022"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p>16.10.2022, 20 Uhr<\/p>\n<p><strong><a href=\"http:\/\/nl.ngbk.de\/lt.php?tid=cUsIUAJXVFJUVRxWUVRQGgYBUwBMCgxXAh9QWlQDBAcJBF0CVgEZA1ZWBFIBBlQaAVRUUUwGDABTH1BbBAIZVAwGDFBRUVYGAFVQTwUEAFEEDldSTAUPVQYfBQEBUhlRDVMPSwYGUwJQWVMEBgJRAA\">X Properties \u2013 die Recherche, das Berliner Heft und die eutopischen Aussichten<\/a><\/strong><br \/>\nMit der Projektgruppe und G\u00e4sten<br \/>\nOrt: nGbK, Oranienstra\u00dfe 25, 10999 Berlin<\/p>\n<p><a href=\"https:\/\/ngbk.de\/de\/show\/761\/x-properties-die-recherche-das-berliner-heft-und-die-eutopischen-aussichten\" target=\"_blank\" rel=\"noopener\">mehr<\/a> zur Veranstaltung<\/p>","protected":false},"excerpt":{"rendered":"<p>16.10.2022, 20 Uhr X Properties \u2013 die Recherche, das Berliner Heft und die eutopischen Aussichten Mit der Projektgruppe und G\u00e4sten Ort: nGbK, Oranienstra\u00dfe 25, 10999 Berlin mehr zur Veranstaltung<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11710","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DISKUSSION BERLINER HEFTE 2022 &#8211; EECLECTIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DISKUSSION BERLINER HEFTE 2022 &#8211; EECLECTIC\" \/>\n<meta property=\"og:description\" content=\"16.10.2022, 20 Uhr X Properties \u2013 die Recherche, das Berliner Heft und die eutopischen Aussichten Mit der Projektgruppe und G\u00e4sten Ort: nGbK, Oranienstra\u00dfe 25, 10999 Berlin mehr zur Veranstaltung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/\" \/>\n<meta property=\"og:site_name\" content=\"EECLECTIC\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-04T19:10:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-03T16:50:34+00:00\" \/>\n<meta name=\"author\" content=\"janine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"janine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/eeclectic.de\/diskussion-berliner-hefte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eeclectic.de\/diskussion-berliner-hefte\/\"},\"author\":{\"name\":\"janine\",\"@id\":\"https:\/\/eeclectic.de\/#\/schema\/person\/16c028fa621a9535e208da57a8aeec9d\"},\"headline\":\"DISKUSSION BERLINER HEFTE 2022\",\"datePublished\":\"2022-09-04T19:10:23+00:00\",\"dateModified\":\"2023-02-03T16:50:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eeclectic.de\/diskussion-berliner-hefte\/\"},\"wordCount\":31,\"publisher\":{\"@id\":\"https:\/\/eeclectic.de\/#organization\"},\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/\",\"url\":\"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/\",\"name\":\"DISKUSSION BERLINER HEFTE 2022 &#8211; EECLECTIC\",\"isPartOf\":{\"@id\":\"https:\/\/eeclectic.de\/en\/#website\"},\"datePublished\":\"2022-09-04T19:10:23+00:00\",\"dateModified\":\"2023-02-03T16:50:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eeclectic.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DISKUSSION BERLINER HEFTE 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eeclectic.de\/en\/#website\",\"url\":\"https:\/\/eeclectic.de\/en\/\",\"name\":\"EECLECTIC\",\"description\":\"Digital Publishing for Visual Culture\",\"publisher\":{\"@id\":\"https:\/\/eeclectic.de\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eeclectic.de\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eeclectic.de\/en\/#organization\",\"name\":\"EECLECTIC\",\"url\":\"https:\/\/eeclectic.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/eeclectic.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eeclectic.de\/wp-content\/uploads\/2018\/03\/ee-logo.svg\",\"contentUrl\":\"https:\/\/eeclectic.de\/wp-content\/uploads\/2018\/03\/ee-logo.svg\",\"caption\":\"EECLECTIC\"},\"image\":{\"@id\":\"https:\/\/eeclectic.de\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/eeclectic.de\/#\/schema\/person\/16c028fa621a9535e208da57a8aeec9d\",\"name\":\"janine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/eeclectic.de\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a779ac6e5cf498bf231c9f81f889d9b5a9f28e60dcc188ac29549dd2c60b76c3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a779ac6e5cf498bf231c9f81f889d9b5a9f28e60dcc188ac29549dd2c60b76c3?s=96&d=mm&r=g\",\"caption\":\"janine\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DISKUSSION BERLINER HEFTE 2022 &#8211; EECLECTIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/","og_locale":"en_US","og_type":"article","og_title":"DISKUSSION BERLINER HEFTE 2022 &#8211; EECLECTIC","og_description":"16.10.2022, 20 Uhr X Properties \u2013 die Recherche, das Berliner Heft und die eutopischen Aussichten Mit der Projektgruppe und G\u00e4sten Ort: nGbK, Oranienstra\u00dfe 25, 10999 Berlin mehr zur Veranstaltung","og_url":"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/","og_site_name":"EECLECTIC","article_published_time":"2022-09-04T19:10:23+00:00","article_modified_time":"2023-02-03T16:50:34+00:00","author":"janine","twitter_card":"summary_large_image","twitter_misc":{"Written by":"janine"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eeclectic.de\/diskussion-berliner-hefte\/#article","isPartOf":{"@id":"https:\/\/eeclectic.de\/diskussion-berliner-hefte\/"},"author":{"name":"janine","@id":"https:\/\/eeclectic.de\/#\/schema\/person\/16c028fa621a9535e208da57a8aeec9d"},"headline":"DISKUSSION BERLINER HEFTE 2022","datePublished":"2022-09-04T19:10:23+00:00","dateModified":"2023-02-03T16:50:34+00:00","mainEntityOfPage":{"@id":"https:\/\/eeclectic.de\/diskussion-berliner-hefte\/"},"wordCount":31,"publisher":{"@id":"https:\/\/eeclectic.de\/#organization"},"articleSection":["Allgemein"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/","url":"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/","name":"DISKUSSION BERLINER HEFTE 2022 &#8211; EECLECTIC","isPartOf":{"@id":"https:\/\/eeclectic.de\/en\/#website"},"datePublished":"2022-09-04T19:10:23+00:00","dateModified":"2023-02-03T16:50:34+00:00","breadcrumb":{"@id":"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eeclectic.de\/en\/diskussion-berliner-hefte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eeclectic.de\/en\/"},{"@type":"ListItem","position":2,"name":"DISKUSSION BERLINER HEFTE 2022"}]},{"@type":"WebSite","@id":"https:\/\/eeclectic.de\/en\/#website","url":"https:\/\/eeclectic.de\/en\/","name":"EECLECTIC","description":"Digital Publishing for Visual Culture","publisher":{"@id":"https:\/\/eeclectic.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eeclectic.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eeclectic.de\/en\/#organization","name":"EECLECTIC","url":"https:\/\/eeclectic.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eeclectic.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/eeclectic.de\/wp-content\/uploads\/2018\/03\/ee-logo.svg","contentUrl":"https:\/\/eeclectic.de\/wp-content\/uploads\/2018\/03\/ee-logo.svg","caption":"EECLECTIC"},"image":{"@id":"https:\/\/eeclectic.de\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eeclectic.de\/#\/schema\/person\/16c028fa621a9535e208da57a8aeec9d","name":"janine","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eeclectic.de\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a779ac6e5cf498bf231c9f81f889d9b5a9f28e60dcc188ac29549dd2c60b76c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a779ac6e5cf498bf231c9f81f889d9b5a9f28e60dcc188ac29549dd2c60b76c3?s=96&d=mm&r=g","caption":"janine"}}]}},"_links":{"self":[{"href":"https:\/\/eeclectic.de\/en\/wp-json\/wp\/v2\/posts\/11710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eeclectic.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eeclectic.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eeclectic.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/eeclectic.de\/en\/wp-json\/wp\/v2\/comments?post=11710"}],"version-history":[{"count":3,"href":"https:\/\/eeclectic.de\/en\/wp-json\/wp\/v2\/posts\/11710\/revisions"}],"predecessor-version":[{"id":13484,"href":"https:\/\/eeclectic.de\/en\/wp-json\/wp\/v2\/posts\/11710\/revisions\/13484"}],"wp:attachment":[{"href":"https:\/\/eeclectic.de\/en\/wp-json\/wp\/v2\/media?parent=11710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eeclectic.de\/en\/wp-json\/wp\/v2\/categories?post=11710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eeclectic.de\/en\/wp-json\/wp\/v2\/tags?post=11710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}